{"id":2587,"date":"2023-10-19T16:57:41","date_gmt":"2023-10-19T19:57:41","guid":{"rendered":"https:\/\/www.infodolar.com\/blog\/?p=2587"},"modified":"2023-10-19T16:57:45","modified_gmt":"2023-10-19T19:57:45","slug":"resultados-de-la-encuesta-si-se-dolariza-cuanto-seria-tu-sueldo-en-dolares","status":"publish","type":"post","link":"https:\/\/www.infodolar.com\/blog\/index.php\/resultados-de-la-encuesta-si-se-dolariza-cuanto-seria-tu-sueldo-en-dolares\/","title":{"rendered":"Resultados de la encuesta \u00abSi se dolariza, cu\u00e1nto ser\u00eda tu sueldo en d\u00f3lares\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Entre el<strong> lunes 16 y el martes 17 de octubre de 2023<\/strong> realizamos una encuesta en el <a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/infodolar\/\" target=\"_blank\">Instagram de InfoDolar<\/a> para conocer la opini\u00f3n de nuestros usuarios acerca de si se dolariza cu\u00e1l ser\u00eda el impacto en su sueldo -medido en t\u00e9rminos de d\u00f3lar blue-. Conoc\u00e9 el resultado de la encuesta (que respondieron 8.578 personas) en la presente nota.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La encuesta <strong>\u201cSi se dolariza, cu\u00e1nto ser\u00eda tu sueldo en d\u00f3lares blue\u201d<\/strong> estuvo 24 horas disponible en Instagram.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las opciones eran las siguientes:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Mayor<\/li><li>Igual<\/li><li>Menor<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n, se presentan los resultados de la encuesta:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"459\" height=\"807\" src=\"https:\/\/www.infodolar.com\/blog\/wp-content\/uploads\/2023\/10\/image-9.png\" alt=\"\" class=\"wp-image-2589\" srcset=\"https:\/\/www.infodolar.com\/blog\/wp-content\/uploads\/2023\/10\/image-9.png 459w, https:\/\/www.infodolar.com\/blog\/wp-content\/uploads\/2023\/10\/image-9-171x300.png 171w\" sizes=\"auto, (max-width: 459px) 100vw, 459px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Como se puede observar <strong>el 47 % de los encuestados opina que su sueldo (medido en t\u00e9rminos de dolar blue) ser\u00eda \u00abmenor\u00bb<\/strong>. El <strong>39 % opina que su sueldo ser\u00eda \u00abigual\u00bb<\/strong> y <strong>s\u00f3lo el 14% de los encuestados cree en el caso de dolarizar la econom\u00eda su sueldo ser\u00eda \u00abmayor\u00bb<\/strong>. <strong> <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto, cabe recordar que en una reciente encuesta (12 de octubre de 2023), el <strong>51% de las personas se manifest\u00f3 a favor de la dolarizaci\u00f3n<\/strong> (<a href=\"https:\/\/www.infodolar.com\/blog\/index.php\/resultados-de-la-encuesta-estas-a-favor-de-la-dolarizacion\/\">Est\u00e1s a favor de la dolarizaci\u00f3n<\/a>). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En total respondieron la encuesta <strong>\u201cSi se dolariza, cu\u00e1nto ser\u00eda tu sueldo en d\u00f3lares blue\u201d<\/strong> un total de 8.578 personas<\/strong>. El detalle de cantidad de personas por cada respuesta seleccionada fue el siguiente:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"441\" height=\"211\" src=\"https:\/\/www.infodolar.com\/blog\/wp-content\/uploads\/2023\/10\/image-8.png\" alt=\"\" class=\"wp-image-2588\" srcset=\"https:\/\/www.infodolar.com\/blog\/wp-content\/uploads\/2023\/10\/image-8.png 441w, https:\/\/www.infodolar.com\/blog\/wp-content\/uploads\/2023\/10\/image-8-300x144.png 300w\" sizes=\"auto, (max-width: 441px) 100vw, 441px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Otras encuestas de InfoDolar:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.infodolar.com\/blog\/index.php\/resultados-de-la-encuesta-estas-a-favor-de-la-dolarizacion\/\">Est\u00e1s a favor de la dolarizaci\u00f3n<\/a><\/li><li><a href=\"https:\/\/www.infodolar.com\/blog\/index.php\/resultados-encuesta-cual-sera-el-precio-del-dolar-blue-despues-de-las-elecciones-del-22-de-octubre\/\">Cu\u00e1l ser\u00e1 el precio del d\u00f3lar blue despu\u00e9s de las elecciones del 22 de octubre<\/a><\/li><li><a href=\"https:\/\/www.infodolar.com\/blog\/index.php\/resultados-encuesta-las-medidas-de-massa-llevaran-el-dolar-a\/\">Las medidas de Massa llevar\u00e1n el d\u00f3lar a&#8230;<\/a><\/li><li><a href=\"https:\/\/www.infodolar.com\/blog\/index.php\/resultados-encuesta-compraste-alguna-vez-dolar-cripto\/\">Compraste alguna vez d\u00f3lar cripto<\/a><\/li><li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.infodolar.com\/blog\/index.php\/resultados-encuesta-compraste-dolares-en-los-ultimos-30-dias\/\" target=\"_blank\">Compraste d\u00f3lares en los \u00faltimos 30 d\u00edas<\/a><\/li><li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.infodolar.com\/blog\/index.php\/resultados-encuesta-a-cuanto-va-a-estar-el-dolar-blue-el-lunes-despues-de-las-elecciones\/\" target=\"_blank\">A cu\u00e1nto va a estar el d\u00f3lar blue el lunes despu\u00e9s de las elecciones<\/a><\/li><li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.infodolar.com\/blog\/index.php\/resultados-encuesta-a-cuanto-va-a-estar-el-dolar-blue-el-lunes-despues-de-las-paso\/\" target=\"_blank\">A cu\u00e1nto va a estar el d\u00f3lar blue el lunes despu\u00e9s de las PASO<\/a><\/li><li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.infodolar.com\/blog\/index.php\/encuestas-sobre-extraccion-de-dolares\/\" target=\"_blank\">Extracci\u00f3n de d\u00f3lares del banco<\/a><\/li><li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.infodolar.com\/blog\/index.php\/dolar-o-plazo-fijo-que-prefieren-los-argentinos\/\" target=\"_blank\">\u00bfD\u00f3lar o plazo fijo?<\/a><\/li><li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.infodolar.com\/blog\/index.php\/que-prefieren-los-argentinos-para-ahorrar-dolar-o-euro\/\" target=\"_blank\">Qu\u00e9 prefieren los argentinos para ahorrar: \u00bfD\u00f3lar o Euro?<\/a><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Entre el lunes 16 y el martes 17 de octubre de 2023 realizamos una encuesta en el Instagram de InfoDolar para conocer la opini\u00f3n de nuestros usuarios acerca de si se dolariza cu\u00e1l ser\u00eda el impacto en su sueldo -medido en t\u00e9rminos de d\u00f3lar blue-. Conoc\u00e9 el resultado de la encuesta (que respondieron 8.578 personas) [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2589,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[4,151,312],"tags":[],"class_list":["post-2587","post","type-post","status-publish","format-standard","has-post-thumbnail","category-dolar","category-dolar-blue","category-encuestas","entry"],"_links":{"self":[{"href":"https:\/\/www.infodolar.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/2587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infodolar.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.infodolar.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.infodolar.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infodolar.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=2587"}],"version-history":[{"count":0,"href":"https:\/\/www.infodolar.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/2587\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.infodolar.com\/blog\/index.php\/wp-json\/wp\/v2\/media\/2589"}],"wp:attachment":[{"href":"https:\/\/www.infodolar.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=2587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.infodolar.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=2587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.infodolar.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=2587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}